{"id":1042,"date":"2022-03-14T16:53:21","date_gmt":"2022-03-14T19:53:21","guid":{"rendered":"https:\/\/oolharoftalmologia.com.br\/?page_id=1042"},"modified":"2022-03-15T08:16:55","modified_gmt":"2022-03-15T11:16:55","slug":"consultas","status":"publish","type":"page","link":"https:\/\/oolharoftalmologia.com.br\/index.php\/consultas\/","title":{"rendered":"Consultas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1042\" class=\"elementor elementor-1042\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac6ea4l elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac6ea4l\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f49a1ee\" data-id=\"f49a1ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da3ecf1 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"da3ecf1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e61ffae\" data-id=\"e61ffae\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbd9730 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"bbd9730\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/oolharoftalmologia.com.br\/index.php\/consulta\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-eye\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/oolharoftalmologia.com.br\/index.php\/consulta\" >\n\t\t\t\t\t\tConsulta de Rotina\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tClique no acima para ver valores\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e3722d7\" data-id=\"e3722d7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c7562c elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"3c7562c\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/oolharoftalmologia.com.br\/index.php\/consulta\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-glasses\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/oolharoftalmologia.com.br\/index.php\/consulta\" >\n\t\t\t\t\t\tConsulta para Especialidades\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tClique acima para ver valores\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a18818f\" data-id=\"a18818f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21c6277 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"21c6277\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a class=\"elementor-icon elementor-animation-\" href=\"https:\/\/oolharoftalmologia.com.br\/index.php\/consulta\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hand-holding-medical\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"https:\/\/oolharoftalmologia.com.br\/index.php\/consulta\" >\n\t\t\t\t\t\tPronto Atendimento\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tClique acima para ver valores\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Consulta de Rotina Clique no acima para ver valores Consulta para Especialidades Clique acima para ver valores Pronto Atendimento Clique acima para ver valores<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"_links":{"self":[{"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1042"}],"collection":[{"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":11,"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1042\/revisions"}],"predecessor-version":[{"id":1090,"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1042\/revisions\/1090"}],"wp:attachment":[{"href":"https:\/\/oolharoftalmologia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}